{"id":5712,"date":"2026-03-27T17:22:20","date_gmt":"2026-03-27T21:22:20","guid":{"rendered":"https:\/\/suttonjazz.com\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/"},"modified":"2026-04-05T07:22:38","modified_gmt":"2026-04-05T11:22:38","slug":"year-round-jazz-sutton-broueriemarie-neige-chatelain-trio","status":"publish","type":"tribe_events","link":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/","title":{"rendered":"<span style=\"font-size:12px\">YEAR-ROUND JAZZ &#8211; SUTTON BROU\u00cbRIE<\/span><br>Marie Neige Chatelain Trio"},"content":{"rendered":"<p>Velvet Trio presents jazz standards in french and in english, in an intimate and sophisticated setting.<\/p>\n<p>Reservations: 450-538-0005<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Claude Prud&#8217;homme, guitar; Michael Hynes, piano; and Marie Neige Chatelain, vocals<br \/>\nReservations: 450-538-0005<\/p>\n","protected":false},"author":11,"featured_media":5724,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"tags":[],"tribe_events_cat":[73,99],"class_list":["post-5712","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-jazz-at-the-brouerie","tribe_events_cat-jazz-in-spring","cat_jazz-at-the-brouerie","cat_jazz-in-spring"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>YEAR-ROUND JAZZ - SUTTON BROU\u00cbRIEMarie Neige Chatelain Trio - Sutton Jazz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"YEAR-ROUND JAZZ - SUTTON BROU\u00cbRIEMarie Neige Chatelain Trio - Sutton Jazz\" \/>\n<meta property=\"og:description\" content=\"Claude Prud&#039;homme, guitar; Michael Hynes, piano; and Marie Neige Chatelain, vocals Reservations: 450-538-0005\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/\" \/>\n<meta property=\"og:site_name\" content=\"Sutton Jazz\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/suttonjazz\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T11:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suttonjazz.com\/wp-content\/uploads\/2026\/03\/Velvet-Cafe-1-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/\",\"url\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/\",\"name\":\"YEAR-ROUND JAZZ - SUTTON BROU\u00cbRIE Marie Neige Chatelain Trio - Sutton Jazz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suttonjazz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Velvet-Cafe-1-1-1.png\",\"datePublished\":\"2026-03-27T21:22:20+00:00\",\"dateModified\":\"2026-04-05T11:22:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suttonjazz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Velvet-Cafe-1-1-1.png\",\"contentUrl\":\"https:\\\/\\\/suttonjazz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Velvet-Cafe-1-1-1.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/event\\\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"YEAR-ROUND JAZZ &#8211; SUTTON BROU\u00cbRIEMarie Neige Chatelain Trio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/\",\"name\":\"Sutton Jazz\",\"description\":\"Le plaisir de jazzer avec vous!\",\"publisher\":{\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/#organization\",\"name\":\"Festival de Jazz de Sutton\",\"url\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suttonjazz.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/V4-MaestroTimes-16x9-tour.jpg\",\"contentUrl\":\"https:\\\/\\\/suttonjazz.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/V4-MaestroTimes-16x9-tour.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Festival de Jazz de Sutton\"},\"image\":{\"@id\":\"https:\\\/\\\/suttonjazz.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/suttonjazz\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"YEAR-ROUND JAZZ - SUTTON BROU\u00cbRIEMarie Neige Chatelain Trio - Sutton Jazz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/","og_locale":"en_US","og_type":"article","og_title":"YEAR-ROUND JAZZ - SUTTON BROU\u00cbRIEMarie Neige Chatelain Trio - Sutton Jazz","og_description":"Claude Prud'homme, guitar; Michael Hynes, piano; and Marie Neige Chatelain, vocals Reservations: 450-538-0005","og_url":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/","og_site_name":"Sutton Jazz","article_publisher":"https:\/\/www.facebook.com\/suttonjazz\/","article_modified_time":"2026-04-05T11:22:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/suttonjazz.com\/wp-content\/uploads\/2026\/03\/Velvet-Cafe-1-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/","url":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/","name":"YEAR-ROUND JAZZ - SUTTON BROU\u00cbRIE Marie Neige Chatelain Trio - Sutton Jazz","isPartOf":{"@id":"https:\/\/suttonjazz.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/#primaryimage"},"image":{"@id":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/#primaryimage"},"thumbnailUrl":"https:\/\/suttonjazz.com\/wp-content\/uploads\/2026\/03\/Velvet-Cafe-1-1-1.png","datePublished":"2026-03-27T21:22:20+00:00","dateModified":"2026-04-05T11:22:38+00:00","breadcrumb":{"@id":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/#primaryimage","url":"https:\/\/suttonjazz.com\/wp-content\/uploads\/2026\/03\/Velvet-Cafe-1-1-1.png","contentUrl":"https:\/\/suttonjazz.com\/wp-content\/uploads\/2026\/03\/Velvet-Cafe-1-1-1.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/suttonjazz.com\/en\/event\/year-round-jazz-sutton-broueriemarie-neige-chatelain-trio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/suttonjazz.com\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/suttonjazz.com\/en\/events\/"},{"@type":"ListItem","position":3,"name":"YEAR-ROUND JAZZ &#8211; SUTTON BROU\u00cbRIEMarie Neige Chatelain Trio"}]},{"@type":"WebSite","@id":"https:\/\/suttonjazz.com\/en\/#website","url":"https:\/\/suttonjazz.com\/en\/","name":"Sutton Jazz","description":"Le plaisir de jazzer avec vous!","publisher":{"@id":"https:\/\/suttonjazz.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suttonjazz.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/suttonjazz.com\/en\/#organization","name":"Festival de Jazz de Sutton","url":"https:\/\/suttonjazz.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/suttonjazz.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/suttonjazz.com\/wp-content\/uploads\/2022\/06\/V4-MaestroTimes-16x9-tour.jpg","contentUrl":"https:\/\/suttonjazz.com\/wp-content\/uploads\/2022\/06\/V4-MaestroTimes-16x9-tour.jpg","width":1600,"height":900,"caption":"Festival de Jazz de Sutton"},"image":{"@id":"https:\/\/suttonjazz.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/suttonjazz\/"]}]}},"_links":{"self":[{"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/tribe_events\/5712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":1,"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/tribe_events\/5712\/revisions"}],"predecessor-version":[{"id":5726,"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/tribe_events\/5712\/revisions\/5726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/media\/5724"}],"wp:attachment":[{"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/media?parent=5712"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/tags?post=5712"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/suttonjazz.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=5712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}